{"id":15348,"date":"2017-11-12T18:40:06","date_gmt":"2017-11-12T17:40:06","guid":{"rendered":"http:\/\/vttescapade.fr\/wp\/?p=15348"},"modified":"2017-11-12T21:55:46","modified_gmt":"2017-11-12T20:55:46","slug":"il-etait-un-foie","status":"publish","type":"post","link":"https:\/\/vttescapade.fr\/wp\/il-etait-un-foie\/","title":{"rendered":"Il \u00e9tait un foie &#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15364\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1.jpg\" alt=\"\" height=\"622\" width=\"1300\" srcset=\"https:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1.jpg 1300w, https:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1-300x144.jpg 300w, https:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1-768x367.jpg 768w, https:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1-1024x490.jpg 1024w, https:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1-250x120.jpg 250w, https:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/lahage_team-1-150x72.jpg 150w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/><\/a>Il \u00e9tait &#8230; un de ces dimanche matin \u00e0 ne pas mettre un v\u00e9t\u00e9tiste dehors dans ce crachin annonciateur de matin\u00e9e compliqu\u00e9e&#8230; Et pourtant, pour une fois, j&#8217;arrive le premier chez Ivan, la joyeuse troupe (Bruno, f\u00e9f\u00e9, Alain, reAlain et Quentin) ne tarde pas \u00e0 d\u00e9bouler aussi. Manque juste Nico, surement rest\u00e9 au lit ou alors en panne de son nouveau jouet nucl\u00e9aire&#8230; Apr\u00e8s le petit Caf\u00e9 qui va bien et sous l&#8217;impulsion d&#8217;Alain et Ivan le local de l&#8217;\u00e9tape, nous prenons la direction des chemins de traverse persuad\u00e9s que la bruine n&#8217;est que passag\u00e8re &#8230;<\/p>\n<p style=\"text-align: justify;\">Rapidement les Djeuns (Quentin et Jules)&nbsp; passent aux avant-postes sur ce terrain bien gras mais qui reste roulant malgr\u00e9 de beaux tapis de feuilles mortes glissantes juste ce qu&#8217;il faut. Apr\u00e8s de belles alternances de petites routes puis de pistes tout aussi roulantes, nous retrouvons sans encombre la for\u00eat de Lahage pour quelques tournicotages bossus de saison. Ca glisse grave, les chemins \u00e9tant bien imbib\u00e9s. F\u00e9f\u00e9 et Alain nous guident encore pour quelques belles variantes toujours sous ce crachin ininterrompu et apr\u00e8s une ultime boucle, nous enquillons le fameux long single en sous bois, bien feuillu pour une s\u00e9quence des plus sympathiques. L&#8217;heure tourne&#8230; c&#8217;est donc sans d&#8217;autre ultime bifurcation que nous retrouvons la chaumi\u00e8re d&#8217;Ivan pour un ap\u00e9ro en r\u00e8gle&#8230;<\/p>\n<p style=\"text-align: justify;\">Bien au chaud, apr\u00e8s un brin de toilette, nous cl\u00f4turons cette matin\u00e9e entre charcutaille et un superbe lobe de foie gras maison (800g quand m\u00eame !) sans oublier l&#8217;excellent Tariquet qui va bien.<\/p>\n<p>Encore, une belle sortie Vttescapade, revigorante surtout sur la fin &#8230;&nbsp; Merci Ivan pour l&#8217;invitation et toute la troupe pour la bonne humeur habituelle !<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4497.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-15350\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4497-150x120.jpg\" alt=\"\" height=\"120\" width=\"150\"><\/a>&nbsp; <a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4505.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-15351\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4505-150x120.jpg\" alt=\"\" height=\"120\" width=\"150\"><\/a>&nbsp; <a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4510.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-15352\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4510-150x120.jpg\" alt=\"\" height=\"120\" width=\"150\"><\/a>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4514.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-15353\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4514-150x120.jpg\" alt=\"\" height=\"120\" width=\"150\"><\/a>&nbsp; <a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4515.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-15354\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4515-150x120.jpg\" alt=\"\" height=\"120\" width=\"150\">&nbsp;&nbsp;<\/a><a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4511.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-15356\" src=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4511-150x120.jpg\" alt=\"\" height=\"120\" width=\"150\"><\/a><a href=\"http:\/\/vttescapade.fr\/wp\/wp-content\/upload\/2017\/11\/IMG_4515.jpg\">&nbsp; <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il \u00e9tait &#8230; un de ces dimanche matin \u00e0 ne pas mettre un v\u00e9t\u00e9tiste dehors dans ce crachin annonciateur de matin\u00e9e compliqu\u00e9e&#8230; Et pourtant, pour une fois, j&#8217;arrive le premier chez Ivan, la joyeuse troupe (Bruno, f\u00e9f\u00e9, Alain, reAlain et Quentin) ne tarde pas \u00e0\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/vttescapade.fr\/wp\/il-etait-un-foie\/\">Et la suite &#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-15348","post","type-post","status-publish","format-standard","hentry","category-dans-le-coin"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1xCt8-3Zy","_links":{"self":[{"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/posts\/15348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/comments?post=15348"}],"version-history":[{"count":0,"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/posts\/15348\/revisions"}],"wp:attachment":[{"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/media?parent=15348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/categories?post=15348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vttescapade.fr\/wp\/wp-json\/wp\/v2\/tags?post=15348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}